{"id":4145,"date":"2016-08-11T13:06:41","date_gmt":"2016-08-11T13:06:41","guid":{"rendered":"http:\/\/ambicmain.wpengine.com\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg"},"modified":"2025-06-17T11:30:49","modified_gmt":"2025-06-17T11:30:49","slug":"md001-multidipper-complete-web-2","status":"inherit","type":"attachment","link":"https:\/\/ambic.co.uk\/es\/products\/teat-dipping\/multidipper\/md001-multidipper-complete-web-2\/","title":{"rendered":"MD001-MultiDipper-Complete-web"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"attachment_category":[],"attachment_tag":[],"class_list":["post-4145","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg\" \/>\n<meta property=\"og:site_name\" content=\"AMBIC Equipment Ltd UK\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T11:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ambicequipment\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MD001-MultiDipper-Complete-web.jpg\",\"url\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MD001-MultiDipper-Complete-web.jpg\",\"name\":\"MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#website\"},\"datePublished\":\"2016-08-11T13:06:41+00:00\",\"dateModified\":\"2025-06-17T11:30:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MD001-MultiDipper-Complete-web.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MD001-MultiDipper-Complete-web.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MD001-MultiDipper-Complete-web.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ambic.co.uk\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/ambic.co.uk\\\/es\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Products: Teat Dipping\",\"item\":\"https:\\\/\\\/ambic.co.uk\\\/es\\\/products\\\/teat-dipping\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Products: Teat Dipping | MultiDipper\",\"item\":\"https:\\\/\\\/ambic.co.uk\\\/es\\\/products\\\/teat-dipping\\\/multidipper\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"MD001-MultiDipper-Complete-web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#website\",\"url\":\"https:\\\/\\\/ambic.co.uk\\\/\",\"name\":\"AMBIC Equipment Ltd UK\",\"description\":\"AMBIC Equipment Ltd UK\",\"publisher\":{\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ambic.co.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#organization\",\"name\":\"Ambic Equipment\",\"url\":\"https:\\\/\\\/ambic.co.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/ambic-logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/ambic.co.uk\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/ambic-logo-blue.png\",\"width\":803,\"height\":120,\"caption\":\"Ambic Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/ambic.co.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ambicequipment\",\"http:\\\/\\\/ambicequipment\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","og_locale":"es_ES","og_type":"article","og_title":"MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK","og_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","og_site_name":"AMBIC Equipment Ltd UK","article_modified_time":"2025-06-17T11:30:49+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ambicequipment","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","name":"MD001-MultiDipper-Complete-web | AMBIC Equipment Ltd UK","isPartOf":{"@id":"https:\/\/ambic.co.uk\/#website"},"datePublished":"2016-08-11T13:06:41+00:00","dateModified":"2025-06-17T11:30:49+00:00","breadcrumb":{"@id":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ambic.co.uk\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/ambic.co.uk\/es\/products\/"},{"@type":"ListItem","position":3,"name":"Products: Teat Dipping","item":"https:\/\/ambic.co.uk\/es\/products\/teat-dipping\/"},{"@type":"ListItem","position":4,"name":"Products: Teat Dipping | MultiDipper","item":"https:\/\/ambic.co.uk\/es\/products\/teat-dipping\/multidipper\/"},{"@type":"ListItem","position":5,"name":"MD001-MultiDipper-Complete-web"}]},{"@type":"WebSite","@id":"https:\/\/ambic.co.uk\/#website","url":"https:\/\/ambic.co.uk\/","name":"AMBIC Equipment Ltd UK","description":"AMBIC Equipment Ltd UK","publisher":{"@id":"https:\/\/ambic.co.uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ambic.co.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ambic.co.uk\/#organization","name":"Ambic Equipment","url":"https:\/\/ambic.co.uk\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ambic.co.uk\/#\/schema\/logo\/image\/","url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/07\/ambic-logo-blue.png","contentUrl":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/07\/ambic-logo-blue.png","width":803,"height":120,"caption":"Ambic Equipment"},"image":{"@id":"https:\/\/ambic.co.uk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ambicequipment","http:\/\/ambicequipment"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-300x300.jpg 300w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-80x80.jpg 80w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-768x768.jpg 768w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-1030x1030.jpg 1030w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-36x36.jpg 36w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-180x180.jpg 180w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-705x705.jpg 705w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-120x120.jpg 120w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-450x450.jpg 450w, https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1200,"file":"2016\/08\/MD001-MultiDipper-Complete-web.jpg","sizes":{"thumbnail":{"file":"MD001-MultiDipper-Complete-web-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-80x80.jpg"},"medium":{"file":"MD001-MultiDipper-Complete-web-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-300x300.jpg"},"medium_large":{"file":"MD001-MultiDipper-Complete-web-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-768x768.jpg"},"large":{"file":"MD001-MultiDipper-Complete-web-1030x1030.jpg","width":1030,"height":1030,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-1030x1030.jpg"},"widget":{"file":"MD001-MultiDipper-Complete-web-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-36x36.jpg"},"square":{"file":"MD001-MultiDipper-Complete-web-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-180x180.jpg"},"featured":{"file":"MD001-MultiDipper-Complete-web-1200x430.jpg","width":1200,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-1200x430.jpg"},"featured_large":{"file":"MD001-MultiDipper-Complete-web-1200x630.jpg","width":1200,"height":630,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-1200x630.jpg"},"portfolio":{"file":"MD001-MultiDipper-Complete-web-495x400.jpg","width":495,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-495x400.jpg"},"portfolio_small":{"file":"MD001-MultiDipper-Complete-web-260x185.jpg","width":260,"height":185,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-260x185.jpg"},"gallery":{"file":"MD001-MultiDipper-Complete-web-845x684.jpg","width":845,"height":684,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-845x684.jpg"},"magazine":{"file":"MD001-MultiDipper-Complete-web-710x375.jpg","width":710,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-710x375.jpg"},"masonry":{"file":"MD001-MultiDipper-Complete-web-705x705.jpg","width":705,"height":705,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-705x705.jpg"},"entry_with_sidebar":{"file":"MD001-MultiDipper-Complete-web-845x321.jpg","width":845,"height":321,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-845x321.jpg"},"entry_without_sidebar":{"file":"MD001-MultiDipper-Complete-web-1200x423.jpg","width":1200,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-1200x423.jpg"},"shop_thumbnail":{"file":"MD001-MultiDipper-Complete-web-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-120x120.jpg"},"shop_catalog":{"file":"MD001-MultiDipper-Complete-web-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-450x450.jpg"},"shop_single":{"file":"MD001-MultiDipper-Complete-web-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web-450x450.jpg"},"full":{"file":"MD001-MultiDipper-Complete-web.jpg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2606,"source_url":"https:\/\/ambic.co.uk\/wp-content\/uploads\/2016\/08\/MD001-MultiDipper-Complete-web.jpg","_links":{"self":[{"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/media\/4145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/comments?post=4145"}],"wp:term":[{"taxonomy":"attachment_category","embeddable":true,"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/attachment_category?post=4145"},{"taxonomy":"attachment_tag","embeddable":true,"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/attachment_tag?post=4145"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2606,"href":"https:\/\/ambic.co.uk\/es\/wp-json\/wp\/v2\/pages\/2606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}